{"id":669,"date":"2021-09-22T05:01:19","date_gmt":"2021-09-22T08:01:19","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=669"},"modified":"2021-09-22T05:01:19","modified_gmt":"2021-09-22T08:01:19","slug":"cedila-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/","title":{"rendered":"Cedila Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A <strong>Cedila Petrolina<\/strong> tem mais de 35 anos de experi\u00eancia em an\u00e1lises cl\u00ednicas, possui o mais completo servi\u00e7o de diagn\u00f3stico laboratorial da regi\u00e3o, com testes de biologia molecular, teste do pezinho, toxicol\u00f3gicos, teste de DNA, dosagens hormonais e muitos outros.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-670 size-full\" title=\"Cedila Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif\" alt=\"Cedila Petrolina\" width=\"680\" height=\"189\" \/><\/p>\n<h2>Cedila Petrolina Hist\u00f3ria<\/h2>\n<p>Em 1985, come\u00e7ou a construir um sonho, com muito trabalho e muita determina\u00e7\u00e3o. No come\u00e7o foram muitos desafios, que foi superando com garra e esp\u00edrito de equipe.\u00a0Do primeiro microsc\u00f3pio adquirido at\u00e9 os mais modernos equipamentos de tecnologia de ponta que hoje auxilia nas an\u00e1lises, a qualidade foi sempre a maior preocupa\u00e7\u00e3o. Com isto tanto os m\u00e9dicos como os pacientes t\u00eam a tranq\u00fcilidade de obter resultados claros e confi\u00e1veis.<\/p>\n<p>Um trabalho, uma empresa, uma marca n\u00e3o se constr\u00f3i do dia para a noite. Hoje, o Cedila \u00e9 refer\u00eancia em an\u00e1lises cl\u00ednicas para os outros laborat\u00f3rios da regi\u00e3o.\u00a0A experi\u00eancia adquirida ao longo dos anos e uma equipe de alt\u00edssimo n\u00edvel, formada exclusivamente por profissionais competentes que est\u00e3o em constante reciclagem, d\u00e3o a seguran\u00e7a para avaliar da melhor forma cada amostra, cada l\u00e2mina. \u00c9 o amadurecimento que s\u00f3 o tempo pode proporcionar.<\/p>\n<p>A excel\u00eancia em qualidade sempre foi o objetivo de todos os que fazem o Cedila. Investimentos em equipamentos de \u00faltima gera\u00e7\u00e3o, cursos de aperfei\u00e7oamento e especializa\u00e7\u00e3o, associados a constantes treinamentos e reciclagens de toda sua equipe, geram a compet\u00eancia que hoje \u00e9 reconhecida pelos meios, m\u00e9dico, acad\u00eamico e social. A prova desta afirmativa \u00e9 que o Cedila \u00e9 monitorado pela Sociedade Brasileira de An\u00e1lises Cl\u00ednicas, recebendo, mensalmente desde sua filia\u00e7\u00e3o, o Certificado de Qualidade T\u00e9cnica no n\u00edvel \u201cExcelente\u201d..<\/p>\n<p>Al\u00e9m disto, o Cedila tamb\u00e9m mant\u00e9m conv\u00eanios com: Universidade Federal de Pernambuco (UNIVASF), Universidade Federal da Bahia, Faculdade Mauricio de Nassau (Recife), para est\u00e1gio de gradua\u00e7\u00e3o dos estudantes de Farm\u00e1cia, Biomedicina, e aperfei\u00e7oamento dos rec\u00e9m-formados.<\/p>\n<h3>Cedila Petrolina Conv\u00eanios<\/h3>\n<p>O Laborat\u00f3rio oferece atendimento a alguns<em> conv\u00eanios <\/em>entre em contato com sua operadora de sa\u00fade e confira a cobertura.<\/p>\n<h3>Cedila Petrolina Pre\u00e7os<\/h3>\n<p>Os pre\u00e7os variam de acordo com os exames realizados. Voc\u00ea pode consulta-los acessando o Facebook ou site do local.<em><br \/>\n<\/em><\/p>\n<h3>Vagas Cedila Petrolina &#8211; Trabalhe Conosco<\/h3>\n<p>Atitude, responsabilidade, resili\u00eancia, criatividade, comprometimento para resultado, e saber trabalhar em equipe s\u00e3o algumas compet\u00eancias necess\u00e1rias para fazer parte do time. Se voc\u00ea tem esse perfil e est\u00e1 em busca de oportunidades em uma empresa l\u00edder de mercado <em>envie agora mesmo seu curr\u00edculo<\/em> para o Cedila Petrolina.<\/p>\n<h3>Hor\u00e1rio de Funcionamento Cedila em Petrolina<\/h3>\n<ul>\n<li><strong>Centro 1:<\/strong> 24 horas<\/li>\n<li><strong>Centro 2:<\/strong> Segunda a Sexta das 07h \u00e0s 19h \/ S\u00e1bado das 07h \u00e0s 12h<\/li>\n<li><strong>Orla:<\/strong> Segunda a Sexta das 06h30 \u00e0s 11h \/ S\u00e1bado das 06h30 \u00e0s 10h30<\/li>\n<\/ul>\n<h3>Onde fica, Endere\u00e7o e Telefone Cedila em Petrolina<\/h3>\n<ul>\n<li><strong>Centro 1:<\/strong> R. Joaquim Nabuco, 798 &#8211; Telefone: (87) 3983-4600<\/li>\n<li><strong>Centro 2:<\/strong> R. Fernandes da Cunha, 22 &#8211; Telefone: (74) 3613-0205<\/li>\n<li><strong>Orla:<\/strong> Av. Cardoso de S\u00e1 &#8211; Telefone: (87) 3024-3333<\/li>\n<\/ul>\n<h4>Outras informa\u00e7\u00f5es e site<\/h4>\n<ul>\n<li>Mais informa\u00e7\u00f5es: <a href=\"http:\/\/www.cedila.com.br\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.cedila.com.br<\/a><\/li>\n<li>CNPJ: 11.475.720\/0003-91<\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o Centro 1<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3936.3193815151917!2d-40.501237685210604!3d-9.39334199326864!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x77370691677a16d0x816b9bdac758172e!2sR.JoaquimNabuco798-CentroPetrolina-PE56304-040!5e0!3m2!1spt-BR!2sbr!4v1632297599143!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Cedila Petrolina tem mais de 35 anos de experi\u00eancia em an\u00e1lises cl\u00ednicas, possui o mais completo servi\u00e7o de diagn\u00f3stico laboratorial da regi\u00e3o, com testes de biologia molecular, teste do pezinho, toxicol\u00f3gicos, teste de DNA, dosagens hormonais e muitos outros. Cedila Petrolina Hist\u00f3ria Em 1985, come\u00e7ou a construir um sonho, com muito trabalho e muita determina\u00e7\u00e3o. No come\u00e7o foram muitos desafios, que foi superando com garra e esp\u00edrito de equipe.\u00a0Do primeiro microsc\u00f3pio adquirido at\u00e9 os mais modernos equipamentos de tecnologia de ponta que hoje auxilia nas an\u00e1lises, a qualidade foi sempre a maior preocupa\u00e7\u00e3o. Com isto tanto os m\u00e9dicos como <\/p>\n","protected":false},"author":1,"featured_media":670,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude-em-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o<\/title>\n<meta name=\"description\" content=\"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o\" \/>\n<meta property=\"og:description\" content=\"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T08:01:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"Cedila Petrolina\",\"datePublished\":\"2021-09-22T08:01:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/\"},\"wordCount\":622,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/LABORATORIO.gif\",\"articleSection\":[\"Sa\u00fade Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/\",\"name\":\"Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/LABORATORIO.gif\",\"datePublished\":\"2021-09-22T08:01:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/LABORATORIO.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/LABORATORIO.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/cedila-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cedila Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o","description":"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o","og_description":"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-09-22T08:01:19+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif","type":"image\/gif"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"Cedila Petrolina","datePublished":"2021-09-22T08:01:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/"},"wordCount":622,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif","articleSection":["Sa\u00fade Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/","name":"Cedila Petrolina: Hist\u00f3ria, Conv\u00eanios, Pre\u00e7os, Vagas, Endere\u00e7o","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif","datePublished":"2021-09-22T08:01:19+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre o ( Cedila em Petrolina ) - Informa\u00e7\u00f5es, hist\u00f3ria, Conv\u00eanios, pre\u00e7os, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/LABORATORIO.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/cedila-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Cedila Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/669\/revisions"}],"predecessor-version":[{"id":671,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/669\/revisions\/671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/670"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}