{"id":689,"date":"2021-09-22T09:07:40","date_gmt":"2021-09-22T12:07:40","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=689"},"modified":"2021-09-22T09:07:40","modified_gmt":"2021-09-22T12:07:40","slug":"ftc-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/","title":{"rendered":"FTC Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Com atua\u00e7\u00e3o de destaque entre as Institui\u00e7\u00f5es de Ensino Superior particular do Estado e um projeto pedag\u00f3gico inovador voltado para a interdisciplinaridade e o empreendedorismo, a Faculdade de Tecnologia e Ci\u00eancias &#8211; <strong>FTC Petrolina<\/strong> &#8211; desde o in\u00edcio de suas atividades, no ano 2000, oferta uma forma\u00e7\u00e3o de qualidade atuando em cinco unidades de ensino presencial nas cidades de Salvador, Feira de Santana, Vit\u00f3ria da Conquista, Jequi\u00e9 e Itabuna.<\/p>\n<p>Com aproximadamente 20 mil estudantes e objetivando proporcionar uma estrutura de qualidade aos seus alunos, de modo que estes venham a colocar em pr\u00e1tica o conhecimento adquirido em sala de aula, a Faculdade disponibiliza diversos n\u00facleos de aprendizagem e laborat\u00f3rios equipados para atender as tr\u00eas \u00e1reas acad\u00eamicas: Ci\u00eancias da Sa\u00fade, Humanas e Exatas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-639 size-full\" title=\"FTC Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif\" alt=\"FTC Petrolina\" width=\"680\" height=\"189\" \/><\/p>\n<p>Al\u00e9m disso, a Institui\u00e7\u00e3o ainda disponibiliza diversas op\u00e7\u00f5es de Financiamento Estudantil que facilitam o pagamento das mensalidades da Gradua\u00e7\u00e3o; mant\u00e9m conv\u00eanios com empresas viabilizando descontos para os colaboradores; proporciona at\u00e9 quatro disciplinas gratuitas em outros cursos para estimular a interdisciplinaridade do seu corpo discente, entre diversas outras atividades com objetivo de formar profissionais criativos, competitivos e empreendedores, capazes de atuar de forma \u00e9tica, humana e cient\u00edfica na sociedade.<\/p>\n<h2>FTC Petrolina Cursos<\/h2>\n<p>Adequada \u00e0s demandas do mercado e com foco voltado para as atividades de cada regi\u00e3o onde est\u00e1 presente, a Rede FTC oferece op\u00e7\u00f5es de gradua\u00e7\u00e3o em todas as \u00e1reas do conhecimento. Sendo assim, a Institui\u00e7\u00e3o disponibiliza desde as tradicionais habilita\u00e7\u00f5es em Administra\u00e7\u00e3o, Odontologia, Nutri\u00e7\u00e3o, Direito, Medicina, Medicina Veterin\u00e1ria e Engenharia, at\u00e9 as mais inovadoras, Ci\u00eancias Aeron\u00e1uticas, Hiperm\u00eddia, Cinema e V\u00eddeo, Biomedicina e Engenharia Mecatr\u00f4nica.<\/p>\n<p>Al\u00e9m da Gradua\u00e7\u00e3o, s\u00e3o oferecidos cursos de P\u00f3s-Gradua\u00e7\u00e3o que atendem as demandas do mercado de trabalho e o primeiro Mestrado Profissional stricto sensu em Bioenergia oferecido no Brasil com funcionamento autorizado pela Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior, do Minist\u00e9rio da Educa\u00e7\u00e3o (Capes \/MEC).<\/p>\n<p>Na modalidade a Dist\u00e2ncia, a FTC EAD formou mais de 30 mil professores graduados nos cursos de Licenciatura em Biologia, Geografia, Hist\u00f3ria, Letras, Matem\u00e1tica e Pedagogia em todo o pa\u00eds, com um grande n\u00famero de aprova\u00e7\u00e3o em concursos p\u00fablicos.<\/p>\n<p>A Faculdade de Tecnologia e Ci\u00eancias ainda oferta <em>cursos<\/em> de Educa\u00e7\u00e3o Profissional T\u00e9cnica de N\u00edvel M\u00e9dio em parceria com a Organiza\u00e7\u00e3o Tecnol\u00f3gica de Ensino (OTE) que \u00e9 uma institui\u00e7\u00e3o autorizada pelo Conselho Estadual de Educa\u00e7\u00e3o do Estado da Bahia.<\/p>\n<p>A OTE Cursos T\u00e9cnicos foi criada para oferecer educa\u00e7\u00e3o profissional e t\u00e9cnica de n\u00edvel m\u00e9dio, motiva\u00e7\u00e3o que surge da necessidade de suprir um hiato entre a forma\u00e7\u00e3o geral de n\u00edvel m\u00e9dio e a de n\u00edvel superior.<\/p>\n<h3>FTC Petrolina Portal do Aluno<\/h3>\n<p>A FTC oferece ao aluno um espa\u00e7o chamado<em> Portal do Aluno <\/em>onde ele pode acessar suas notas, frequencia, material de estudo e agenda de provas. Acesse utilizando seu login e senha.<\/p>\n<h3>FTC Petrolina Mensalidade<\/h3>\n<p>Para maiores informa\u00e7\u00f5es sobre a <em>mensalidade <\/em>entre em contato com a secretaria da faculdade.<\/p>\n<h3>FTC Petrolina Vestibular<\/h3>\n<p>A Faculdade admite alunos atrav\u00e9s de provas de <em>vestibular<\/em>, fique atento ao site para n\u00e3o perder as datas de inscri\u00e7\u00f5es e provas.<\/p>\n<h3>Vagas FTC Petrolina &#8211; Trabalhe Conosco<\/h3>\n<p>A FTC Petrolina disponibiliza<em> vagas de trabalho<\/em> durante todo ano. Para se informar sobre os processos seletivos e se candidatar as vagas acompanhe o site da empresa, onde \u00e9 poss\u00edvel se informar sobre vagas abertas, sal\u00e1rios e compet\u00eancias necess\u00e1rias para se candidatar ao processo.<\/p>\n<h3>Hor\u00e1rio de Funcionamento FTC em Petrolina<\/h3>\n<ul>\n<li>Segunda a Sexta das 08h \u00e0s 20h<\/li>\n<\/ul>\n<h3>Onde fica, Endere\u00e7o e Telefone FTC em Petrolina<\/h3>\n<ul>\n<li>Av. Clementino Coelho, 714 &#8211; Centro &#8211; Petrolina &#8211; PE<\/li>\n<li>Telefone: 0800 056 6666<\/li>\n<\/ul>\n<h4>Outras informa\u00e7\u00f5es e site<\/h4>\n<ul>\n<li>Mais informa\u00e7\u00f5es: <a href=\"https:\/\/www.uniftc.edu.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.uniftc.edu.br<\/a><\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d15745.11689055089!2d-40.5132885!3d-9.3968748!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00xa0285f0844666dba!2sFaculdadeUniFTCPetrolina!5e0!3m2!1spt-BR!2sbr!4v1632312385432!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Com atua\u00e7\u00e3o de destaque entre as Institui\u00e7\u00f5es de Ensino Superior particular do Estado e um projeto pedag\u00f3gico inovador voltado para a interdisciplinaridade e o empreendedorismo, a Faculdade de Tecnologia e Ci\u00eancias &#8211; FTC Petrolina &#8211; desde o in\u00edcio de suas atividades, no ano 2000, oferta uma forma\u00e7\u00e3o de qualidade atuando em cinco unidades de ensino presencial nas cidades de Salvador, Feira de Santana, Vit\u00f3ria da Conquista, Jequi\u00e9 e Itabuna. Com aproximadamente 20 mil estudantes e objetivando proporcionar uma estrutura de qualidade aos seus alunos, de modo que estes venham a colocar em pr\u00e1tica o conhecimento adquirido em sala de aula, <\/p>\n","protected":false},"author":1,"featured_media":639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-em-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular<\/title>\n<meta name=\"description\" content=\"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular\" \/>\n<meta property=\"og:description\" content=\"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-22T12:07:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"FTC Petrolina\",\"datePublished\":\"2021-09-22T12:07:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/\"},\"wordCount\":733,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"articleSection\":[\"Educa\u00e7\u00e3o Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/\",\"name\":\"FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"datePublished\":\"2021-09-22T12:07:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/ftc-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FTC Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular","description":"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular","og_description":"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-09-22T12:07:40+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","type":"image\/gif"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"FTC Petrolina","datePublished":"2021-09-22T12:07:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/"},"wordCount":733,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","articleSection":["Educa\u00e7\u00e3o Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/","name":"FTC Petrolina: Cursos, Portal do Aluno, Mensalidade, Vestibular","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","datePublished":"2021-09-22T12:07:40+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre a ( FTC em Petrolina ) - Informa\u00e7\u00f5es, cursos, portal do aluno, mensalidade, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/ftc-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"FTC Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=689"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/689\/revisions"}],"predecessor-version":[{"id":690,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/689\/revisions\/690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}