{"id":778,"date":"2021-10-06T11:10:50","date_gmt":"2021-10-06T14:10:50","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=778"},"modified":"2021-10-06T11:10:50","modified_gmt":"2021-10-06T14:10:50","slug":"unip-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/","title":{"rendered":"Unip Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A Universidade Paulista (UNIP) em Petrolina tem no ensino de gradua\u00e7\u00e3o a sua principal atividade, desenvolvida por professores conscientes de suas responsabilidades sociais.<\/p>\n<p>A\u00a0<strong>UNIP Petrolina<\/strong>\u00a0oferece Cursos Superiores de Gradua\u00e7\u00e3o Tecnol\u00f3gicos, Cursos Superiores de Gradua\u00e7\u00e3o Tradicionais, P\u00f3s-gradua\u00e7\u00e3o Lato Sensu P\u00f3s-Gradua\u00e7\u00e3o Stricto Sensu e Pronatec.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-639 size-full\" title=\"Unip Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif\" alt=\"Unip Petrolina\" width=\"680\" height=\"189\" \/><\/p>\n<p>A\u00a0UNIP\u00a0tem como miss\u00e3o constituir-se num centro de gera\u00e7\u00e3o e difus\u00e3o do saber, articulando as atividades de ensino, de pesquisa e de extens\u00e3o, em conson\u00e2ncia com as demandas da sociedade contempor\u00e2nea e do mundo do trabalho, respeitando a diversidade e cultivando a solidariedade, a inclus\u00e3o, os valores humanos e a \u00e9tica, visando \u00e0 forma\u00e7\u00e3o de cidad\u00e3os qualificados e potencialmente aptos a contribu\u00edrem para o desenvolvimento s\u00f3cio-econ\u00f4mico da sua regi\u00e3o de influ\u00eancia.<\/p>\n<h2>UNIP Petrolina Vestibular, Cursos e Valores<\/h2>\n<p>A UNIP Petrolinaoferece mais de 40 <em>cursos em diversas \u00e1reas de atua\u00e7\u00e3o<\/em>. Os vestibulares da Universidade Paulista acontecem duas vezes no ano. \u00c9 poss\u00edvel realizar a inscri\u00e7\u00e3o no site da institui\u00e7\u00e3o. A Universidade Paulista de Petrolina trabalha com dois tipos de vestibulares: <em>Prova Tradicional , Prova Agendada, Prova para o Concurso de Bolsas 100% e ENEM (Exame Nacional do Ensino M\u00e9dio)<\/em>\u00a0\u2013 neste caso \u00e9 poss\u00edvel conseguir desconto de 100% no valor total do curso.<\/p>\n<h3>Unip Petrolina Mensalidade<\/h3>\n<p>Para maiores informa\u00e7\u00f5es sobre\u00a0<em>mensalidade<\/em>\u00a0entre em contato com a Unip pelos telefones abaixo.<\/p>\n<h3>Unip Petrolina Portal do Aluno<\/h3>\n<p>No site da Unip existe um espa\u00e7o em que o aluno acompanha sua frequ\u00eancia, suas notas, material de estudo e trabalho. Acesse a\u00a0<em>\u00e1rea do aluno<\/em>\u00a0utilizando seu n\u00famero de matr\u00edcula e a senha previamente cadastrada.<\/p>\n<h3>Unip Petrolina Servi\u00e7os<\/h3>\n<p>A Unip Petrolina oferece os seguintes <em>servi\u00e7os:<\/em><\/p>\n<p><strong>Alunos<\/strong><\/p>\n<ul>\n<li>Atl\u00e9tica UNIP<\/li>\n<li>Carreiras &amp; Mercados<\/li>\n<li>Disciplina On-line<\/li>\n<li>Enade<\/li>\n<li>Est\u00e1gios<\/li>\n<li>FIES<\/li>\n<li>Infraestrutura<\/li>\n<li>Manual de Informa\u00e7\u00f5es Acad\u00eamicas<\/li>\n<li>Sistema On-line de revis\u00e3o b\u00e1sica de conte\u00fados<\/li>\n<li>ProUni<\/li>\n<li>Reabertura de Matr\u00edcula<\/li>\n<li>Secretaria On-line<\/li>\n<li>Solicita\u00e7\u00e3o de Software<\/li>\n<\/ul>\n<p><strong>Biblioteca<\/strong><\/p>\n<ul>\n<li>Acervo e Servi\u00e7os<\/li>\n<li>Pesquisar Acervo<\/li>\n<li>Bases de Dados On-line<\/li>\n<li>Endere\u00e7os Eletr\u00f4nicos<\/li>\n<li>Ficha Catalogr\u00e1fica<\/li>\n<li>Guias de Normaliza\u00e7\u00e3o<\/li>\n<li>Novidades<\/li>\n<li>Regulamento Geral<\/li>\n<\/ul>\n<p><strong>Ex-Alunos<\/strong><\/p>\n<ul>\n<li>Instituto de Acompanhamento Profissional<\/li>\n<\/ul>\n<p><strong>Professores<\/strong><\/p>\n<ul>\n<li>Webmail<\/li>\n<\/ul>\n<p><strong>Suporte ao Ensino<\/strong><\/p>\n<ul>\n<li>CEPPE \u2013 Centro de Estudos e Pesquisas em Psicologia e Pedagogia<\/li>\n<li>Psican\u00e1lise<\/li>\n<li>NIDEM<\/li>\n<li>Praxis<\/li>\n<\/ul>\n<h3>Vagas Unip Petrolina \u2013 Trabalhe Conosco<\/h3>\n<p>A Unip Petrolina disponibiliza <em>vagas de trabalho<\/em>\u00a0durante todo ano. Para se informar sobre os processos seletivos e se candidatar as vagas acompanhe o site da empresa, onde \u00e9 poss\u00edvel se informar sobre vagas abertas, sal\u00e1rios e compet\u00eancias necess\u00e1rias para se candidatar ao processo.<\/p>\n<h3>Hor\u00e1rio de Funcionamento UNIP Petrolina<\/h3>\n<ul>\n<li>Das 8 \u00e0s 22 horas de Segunda \u00e0 Sexta e das 08 \u00e0s 14 aos s\u00e1bados.<\/li>\n<\/ul>\n<h3>Endere\u00e7o e Telefone Faculdade UNIP Petrolina<\/h3>\n<ul>\n<li>R. da Pol\u00f4nia, 2 &#8211; Areia Branca &#8211; Petrolina &#8211; PE<\/li>\n<li>Telefone: <span aria-label=\"Ligar para (87) 3983-2258\">(87) 3983-2258<\/span><\/li>\n<\/ul>\n<h3>Outras informa\u00e7\u00f5es, contato e site:<\/h3>\n<ul>\n<li>Mais informa\u00e7\u00f5es:\u00a0<a href=\"https:\/\/www.unip.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.unip.br<\/a><\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d15745.70413578744!2d-40.4900606!3d-9.3839533!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00x906b03e9257c50f2!2sUNIP-UNIVERSIDADEPAULISTAPOLOPETROLINA!5e0!3m2!1spt-BR!2sbr!4v1633529285264!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Universidade Paulista (UNIP) em Petrolina tem no ensino de gradua\u00e7\u00e3o a sua principal atividade, desenvolvida por professores conscientes de suas responsabilidades sociais. A\u00a0UNIP Petrolina\u00a0oferece Cursos Superiores de Gradua\u00e7\u00e3o Tecnol\u00f3gicos, Cursos Superiores de Gradua\u00e7\u00e3o Tradicionais, P\u00f3s-gradua\u00e7\u00e3o Lato Sensu P\u00f3s-Gradua\u00e7\u00e3o Stricto Sensu e Pronatec. A\u00a0UNIP\u00a0tem como miss\u00e3o constituir-se num centro de gera\u00e7\u00e3o e difus\u00e3o do saber, articulando as atividades de ensino, de pesquisa e de extens\u00e3o, em conson\u00e2ncia com as demandas da sociedade contempor\u00e2nea e do mundo do trabalho, respeitando a diversidade e cultivando a solidariedade, a inclus\u00e3o, os valores humanos e a \u00e9tica, visando \u00e0 forma\u00e7\u00e3o de cidad\u00e3os qualificados e <\/p>\n","protected":false},"author":1,"featured_media":639,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[],"class_list":["post-778","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao-em-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas<\/title>\n<meta name=\"description\" content=\"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas\" \/>\n<meta property=\"og:description\" content=\"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T14:10:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"Unip Petrolina\",\"datePublished\":\"2021-10-06T14:10:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/\"},\"wordCount\":559,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"articleSection\":[\"Educa\u00e7\u00e3o Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/\",\"name\":\"Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"datePublished\":\"2021-10-06T14:10:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/ESCOLA-1.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/unip-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unip Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas","description":"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas","og_description":"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-10-06T14:10:50+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","type":"image\/gif"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"Unip Petrolina","datePublished":"2021-10-06T14:10:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/"},"wordCount":559,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","articleSection":["Educa\u00e7\u00e3o Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/","name":"Unip Petrolina: Cursos, Mensalidade, Portal do Aluno, Servi\u00e7os, Vagas","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","datePublished":"2021-10-06T14:10:50+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre a ( Unip em Petrolina ) - Informa\u00e7\u00f5es, cursos, mensalidade, portal do aluno, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/ESCOLA-1.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/unip-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Unip Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=778"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/778\/revisions"}],"predecessor-version":[{"id":779,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/778\/revisions\/779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/639"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}