{"id":780,"date":"2021-10-06T11:15:34","date_gmt":"2021-10-06T14:15:34","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=780"},"modified":"2021-10-06T11:15:34","modified_gmt":"2021-10-06T14:15:34","slug":"smart-fit-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/","title":{"rendered":"Smart Fit Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>Inaugurada em 2009, a <em>Smart Fit Academias<\/em>\u00a0conta com mais de 250 unidades, localizadas em 22 estados brasileiros e no Distrito Federal, al\u00e9m de presen\u00e7a no Chile, M\u00e9xico, Rep\u00fablica Dominicana, Peru e Col\u00f4mbia.<\/p>\n<div class=\"post-single-content box mark-links entry-content\">\n<div class=\"thecontent\">\n<p>Saiba mais sobre as unidades\u00a0<strong>Smart Fit em Petrolina <\/strong>abaixo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-781 size-full\" title=\"Smart Fit Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg\" alt=\"Smart Fit Petrolina\" width=\"680\" height=\"189\" srcset=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg 680w, https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1-300x83.jpg 300w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/p>\n<p>A rede foi criada com o prop\u00f3sito de democratizar o fitness de alto padr\u00e3o e oferece planos com pre\u00e7os bem acess\u00edveis no\u00a0<em>Brasil<\/em>.\u00a0As unidades contam com professores em sala para orient\u00e1-lo a treinar de forma segura e aut\u00f4noma, com conforto e seguran\u00e7a. O atendimento \u00e9 por ordem de chegada, nossos professores est\u00e3o sempre de camisetas amarelas.<\/p>\n<p>Para que voc\u00ea possa treinar quando e onde quiser, deixamos a Smart Fit sempre bem perto de voc\u00ea! Atualmente, a rede conta com mais de 380 unidades distribu\u00eddas em mais de 24 estados brasileiros e Distrito Federal, al\u00e9m de presen\u00e7a no M\u00e9xico, Chile, Rep\u00fablica Dominicana, Peru e Col\u00f4mbia, somando mais de 1,5 milh\u00e3o de clientes.<\/p>\n<h2>Smart Fit Petrolina Planos<\/h2>\n<p>A Smart Fit possui\u00a0<em>dois planos<\/em>:<\/p>\n<p>Plano Smart: a partir de 59,90, com a op\u00e7\u00e3o do cliente treinar o quanto quiser na unidade escolhida, sem taxa de cancelamento.<\/p>\n<ul>\n<li>Ades\u00e3o: Varia conforme a unidade.<\/li>\n<li>Manuten\u00e7\u00e3o anual: 99,90 e sem taxa de cancelamento.<\/li>\n<li>Atividades: \u00c1rea de muscula\u00e7\u00e3o e aer\u00f3bicos, Aulas especiais.<\/li>\n<li>Condi\u00e7\u00f5es: Isen\u00e7\u00e3o da taxa de cancelamento<\/li>\n<li>Benef\u00edcios Inclusos: Aulas de Gin\u00e1stica<\/li>\n<\/ul>\n<p>Plano Black: A partir de 89,90, com a op\u00e7\u00e3o do cliente treinar em qualquer unidade Smart Fit na Am\u00e9rica Latina.<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"9589494530\" data-ad-format=\"link\" data-full-width-responsive=\"true\" data-adsbygoogle-status=\"done\" data-ad-status=\"unfilled\"><ins id=\"aswift_2_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_2_anchor\"><\/ins><\/ins><\/ins><ins class=\"adsbygoogle\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"1335599994\" data-adsbygoogle-status=\"done\" data-ad-status=\"unfilled\"><ins id=\"aswift_3_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_3_anchor\"><\/ins><\/ins><\/ins><ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"9589494530\" data-ad-format=\"link\" data-full-width-responsive=\"true\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><ins id=\"aswift_4_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_4_anchor\"><\/ins><\/ins><\/ins><br \/>\n<ins class=\"adsbygoogle\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"1335599994\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><ins id=\"aswift_5_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_5_anchor\"><\/ins><\/ins><\/ins><\/p>\n<ul>\n<li>Ades\u00e3o: Varia conforme a unidade.<\/li>\n<li>Manuten\u00e7\u00e3o anual: 99,90. Com taxa de cancelamento.<\/li>\n<li>Atividades: \u00c1rea de muscula\u00e7\u00e3o e aer\u00f3bicos, Aulas especiais<\/li>\n<li>Condi\u00e7\u00f5es: 12 meses de fidelidade<\/li>\n<li>Benef\u00edcios Inclusos: Aulas de Gin\u00e1stica, Cadeira de massagem, Acesso ilimitado \u00e0s demais unidades da rede, Camiseta exclusiva e Treinar com um amigo na sua unidade.<\/li>\n<\/ul>\n<div>\n<h3>Vagas Smart Fit Petrolina \u2013 Trabalhe Conosco<\/h3>\n<p>A Smart Fit Petrolina disponibiliza <em>vagas de trabalho<\/em>\u00a0durante todo ano. Para se informar sobre os processos seletivos e se candidatar as vagas acompanhe o site da empresa, onde \u00e9 poss\u00edvel se informar sobre vagas abertas, sal\u00e1rios e compet\u00eancias necess\u00e1rias para se candidatar ao processo.<\/p>\n<\/div>\n<h3>Hor\u00e1rio de Funcionamento Smart Fit Petrolina<\/h3>\n<ul>\n<li>Segunda a Sexta das 06h \u00e0s 12h e das 16h \u00e0s 20h \/ S\u00e1bado das 09h \u00e0s 18h \/ Domingo das 10h \u00e0s 16h<\/li>\n<\/ul>\n<h3>Endere\u00e7o e Telefone Smart Fit Petrolina<\/h3>\n<ul>\n<li>Av. da Integra\u00e7\u00e3o, 550 &#8211; Vila Eduardo &#8211; Petrolina &#8211; PE<\/li>\n<\/ul>\n<h3>Telefone Smart Fit Petrolina<\/h3>\n<ul>\n<li>Telefone: \u00a0As unidades da Smart Fit em Petrolina n\u00e3o oferecem atendimento telef\u00f4nico, o cidad\u00e3o deve comparecer pessoalmente.<\/li>\n<\/ul>\n<h4>Outras informa\u00e7\u00f5es e site<\/h4>\n<ul>\n<li>Mais informa\u00e7\u00f5es:\u00a0<a href=\"https:\/\/www.smartfit.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.smartfit.com.br<\/a><\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m8!1m3!1d15745.339371257744!2d-40.4855505!3d-9.3919815!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x00x6b54b93d8a73d339!2sAcademiaSmartFit-Petrolina!5e0!3m2!1spt-BR!2sbr!4v1633529671640!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n<\/div>\n<\/div>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Inaugurada em 2009, a Smart Fit Academias\u00a0conta com mais de 250 unidades, localizadas em 22 estados brasileiros e no Distrito Federal, al\u00e9m de presen\u00e7a no Chile, M\u00e9xico, Rep\u00fablica Dominicana, Peru e Col\u00f4mbia. Saiba mais sobre as unidades\u00a0Smart Fit em Petrolina abaixo. A rede foi criada com o prop\u00f3sito de democratizar o fitness de alto padr\u00e3o e oferece planos com pre\u00e7os bem acess\u00edveis no\u00a0Brasil.\u00a0As unidades contam com professores em sala para orient\u00e1-lo a treinar de forma segura e aut\u00f4noma, com conforto e seguran\u00e7a. O atendimento \u00e9 por ordem de chegada, nossos professores est\u00e3o sempre de camisetas amarelas. Para que voc\u00ea possa <\/p>\n","protected":false},"author":1,"featured_media":781,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-em-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o<\/title>\n<meta name=\"description\" content=\"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o\" \/>\n<meta property=\"og:description\" content=\"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-06T14:15:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"Smart Fit Petrolina\",\"datePublished\":\"2021-10-06T14:15:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/\"},\"wordCount\":528,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/smart-fit-fortaleza-1-1.jpg\",\"articleSection\":[\"Lugares em Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/\",\"name\":\"Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/smart-fit-fortaleza-1-1.jpg\",\"datePublished\":\"2021-10-06T14:15:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/smart-fit-fortaleza-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/smart-fit-fortaleza-1-1.jpg\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/smart-fit-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smart Fit Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o","description":"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o","og_description":"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-10-06T14:15:34+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg","type":"image\/jpeg"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"Smart Fit Petrolina","datePublished":"2021-10-06T14:15:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/"},"wordCount":528,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg","articleSection":["Lugares em Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/","name":"Smart Fit Petrolina: Planos, Vagas, Endere\u00e7o","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg","datePublished":"2021-10-06T14:15:34+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre a ( Smart Fit em Petrolina ) - Informa\u00e7\u00f5es, planos, vagas, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/smart-fit-fortaleza-1-1.jpg","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/smart-fit-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Smart Fit Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=780"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/780\/revisions"}],"predecessor-version":[{"id":782,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/780\/revisions\/782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/781"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}