{"id":830,"date":"2021-10-13T08:43:46","date_gmt":"2021-10-13T11:43:46","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=830"},"modified":"2021-10-13T08:43:46","modified_gmt":"2021-10-13T11:43:46","slug":"biblioteca-da-escola-jornalista-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/","title":{"rendered":"Biblioteca da Escola Jornalista Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A<strong> Biblioteca da Escola Jornalista Petrolina<\/strong>, na defini\u00e7\u00e3o tradicional do termo, \u00e9 um local em que s\u00e3o guardados livros, documentos tridimensionais, e demais publica\u00e7\u00f5es para o p\u00fablico estudar, ler, e consultar tais obras. O objetivo da biblioteca \u00e9 a guarda dos livros e demais publica\u00e7\u00f5es em local livre de perigo, onde n\u00e3o sejam roubados, incendiados e demais perigos.<\/p>\n<p>Conservar para que n\u00e3o sejam estragados pois o p\u00fablico manuseia constantemente as obras, ou porque os documentos ficam \u00famidos, quentes e ou em situa\u00e7\u00f5es similares.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-822 size-full\" title=\"Biblioteca da Escola Jornalista Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif\" alt=\"Biblioteca da Escola Jornalista Petrolina\" width=\"680\" height=\"189\" \/><br \/>\nA organiza\u00e7\u00e3o segundo algumas regras para catalogar e arquivar as obras impressas, com intuito de que seja poss\u00edvel de se encontrarem de maneira imediata por meio de classifica\u00e7\u00f5es como autor, assunto, ou diferente carater\u00edstica de import\u00e2ncia.<br \/>\nOs profissionais que lidam com esses objetivos s\u00e3o os bibliotec\u00e1rios, com forma\u00e7\u00e3o em biblioteconomia, curso ensinado em institui\u00e7\u00f5es de ensino superior. Para os visitantes, as bibliotecas t\u00eam tr\u00eas finalidades b\u00e1sicas: estudar, ler e consultar as obras. O p\u00fablico procurador comum das bibliotecas est\u00e1 buscando um estudo sobre um certo tema, de simples leitura por divers\u00e3o, ou de realiza\u00e7\u00e3o de pesquisa a respeito de alguns assuntos. Por essa raz\u00e3o mesmo, h\u00e1 uma grande variedade de pessoas que visitam as bibliotecas quando se \u00e9 tratado de bibliotecas generalistas.<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"9589494530\" data-ad-format=\"link\" data-full-width-responsive=\"true\" data-adsbygoogle-status=\"done\" data-ad-status=\"unfilled\"><ins id=\"aswift_2_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_2_anchor\"><\/ins><\/ins><\/ins><br \/>\n<ins class=\"adsbygoogle\" data-ad-layout=\"in-article\" data-ad-format=\"fluid\" data-ad-client=\"ca-pub-7321736592693252\" data-ad-slot=\"1335599994\" data-adsbygoogle-status=\"done\" data-ad-status=\"filled\"><ins id=\"aswift_3_expand\" tabindex=\"0\" title=\"Advertisement\" aria-label=\"Advertisement\"><ins id=\"aswift_3_anchor\"><\/ins><\/ins><\/ins><\/p>\n<h2>Bibliotecas Hoje<\/h2>\n<p><em>Hoje<\/em>\u00a0em dia, as bibliotecas n\u00e3o s\u00e3o somente guardi\u00e3s de livros, por\u00e9m, da mesma forma, de dicion\u00e1rios, enciclop\u00e9dias, monografias, manuais, documentos tridimensionais, almanaques, atlas, jornais, revistas, mapas, cartazes, manuscritos, filmes, discos, CDs, fitas, VHS, DVDs, BDs, ou bancos de dados (arquivos em PDF ou DOC), fotografias, telas e microfilmes. Revistas e jornais s\u00e3o classificados como material peri\u00f3dico, tamb\u00e9m s\u00e3o organizados e armazenados em uma se\u00e7\u00e3o da biblioteca denominada hemeroteca \u2013 espa\u00e7o pr\u00f3prio para este tipo de material informativo.<br \/>\nPor\u00e9m, o velho conceito de \u201cdep\u00f3sito de livros\u201d foi redefinido para \u201cambiente f\u00edsico ou virtual destinado \u00e0 cole\u00e7\u00e3o de informa\u00e7\u00f5es com a finalidade de auxiliar pesquisas e trabalhos escolares ou para praticar o h\u00e1bito de leitura, material este seja impressos em folhas de papel ou ainda digitalizadas e armazenadas em outros tipos de materiais, tais como CD, fitas, VHS, DVD ou bancos de dados (arquivos em PDF ou DOC).<\/p>\n<h3>Vagas Biblioteca da Escola Jornalista Petrolina \u2013 Trabalhe Conosco<\/h3>\n<p>Atitude, responsabilidade, resili\u00eancia, criatividade, comprometimento para resultado, e saber trabalhar em equipe s\u00e3o algumas compet\u00eancias necess\u00e1rias para fazer parte do time. Se voc\u00ea tem esse perfil e est\u00e1 em busca de oportunidades em uma empresa l\u00edder de mercado\u00a0<em>envie agora mesmo seu curr\u00edculo<\/em> para a Biblioteca da Escola Jornalista Petrolina.<\/p>\n<h3>Hor\u00e1rio de Funcionamento Biblioteca da Escola Jornalista Petrolina<\/h3>\n<ul>\n<li>Segunda a Sexta das 08h \u00e0s 17h<\/li>\n<\/ul>\n<h3>Onde fica, Endere\u00e7o e Telefone Biblioteca da Escola Jornalista Petrolina<\/h3>\n<ul>\n<li>R. Dom Tomaz, 174-256 &#8211; COHAB S\u00e3o Francisco &#8211; Petrolina &#8211; PE<\/li>\n<li>Telefone: (87) 3863-0174<\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3936.256517641876!2d-40.547822885210635!3d-9.39887159326482!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x77370cfd4f9db230xa7957ba3f84c2ac6!2sR.DomTomaz174-COHABSoFranciscoPetrolina-PE56312-670!5e0!3m2!1spt-BR!2sbr!4v1634125369862!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A Biblioteca da Escola Jornalista Petrolina, na defini\u00e7\u00e3o tradicional do termo, \u00e9 um local em que s\u00e3o guardados livros, documentos tridimensionais, e demais publica\u00e7\u00f5es para o p\u00fablico estudar, ler, e consultar tais obras. O objetivo da biblioteca \u00e9 a guarda dos livros e demais publica\u00e7\u00f5es em local livre de perigo, onde n\u00e3o sejam roubados, incendiados e demais perigos. Conservar para que n\u00e3o sejam estragados pois o p\u00fablico manuseia constantemente as obras, ou porque os documentos ficam \u00famidos, quentes e ou em situa\u00e7\u00f5es similares. A organiza\u00e7\u00e3o segundo algumas regras para catalogar e arquivar as obras impressas, com intuito de que seja <\/p>\n","protected":false},"author":1,"featured_media":822,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":["post-830","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bibliotecas-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas<\/title>\n<meta name=\"description\" content=\"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas\" \/>\n<meta property=\"og:description\" content=\"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-13T11:43:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"Biblioteca da Escola Jornalista Petrolina\",\"datePublished\":\"2021-10-13T11:43:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/\"},\"wordCount\":594,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/BIBLIOTECAS-OF.gif\",\"articleSection\":[\"Bibliotecas Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/\",\"name\":\"Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/BIBLIOTECAS-OF.gif\",\"datePublished\":\"2021-10-13T11:43:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/BIBLIOTECAS-OF.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/BIBLIOTECAS-OF.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/biblioteca-da-escola-jornalista-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biblioteca da Escola Jornalista Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas","description":"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas","og_description":"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-10-13T11:43:46+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif","type":"image\/gif"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"Biblioteca da Escola Jornalista Petrolina","datePublished":"2021-10-13T11:43:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/"},"wordCount":594,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif","articleSection":["Bibliotecas Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/","name":"Biblioteca da Escola Jornalista Petrolina: Bibliotecas Hoje, Vagas","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif","datePublished":"2021-10-13T11:43:46+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre a ( Biblioteca da Escola Jornalista em Petrolina ) - Informa\u00e7\u00f5es, hor\u00e1rio de funcionamento, endere\u00e7o e telefone. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/BIBLIOTECAS-OF.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/biblioteca-da-escola-jornalista-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Biblioteca da Escola Jornalista Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=830"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/830\/revisions"}],"predecessor-version":[{"id":831,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/830\/revisions\/831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/822"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}