{"id":890,"date":"2021-10-15T04:52:32","date_gmt":"2021-10-15T07:52:32","guid":{"rendered":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?p=890"},"modified":"2021-10-15T04:52:32","modified_gmt":"2021-10-15T07:52:32","slug":"mirante-serrote-do-urubu-petrolina","status":"publish","type":"post","link":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/","title":{"rendered":"Mirante Serrote do Urubu Petrolina"},"content":{"rendered":"<div class=\"0b65e22e14a0c688f3962b1b52ead64e\" data-index=\"1\" style=\"float: none; margin:5px 0 5px 0; text-align:center;\">\n<!-- PUB 73 - Responsivo Horizontal -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:block\"\r\n     data-ad-client=\"ca-pub-7321736592693252\"\r\n     data-ad-slot=\"3087950420\"\r\n     data-ad-format=\"auto\"\r\n     data-full-width-responsive=\"true\"><\/ins>\r\n<script>\r\n     (adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>O <strong>Mirante Serrote do Urubu Petrolina<\/strong> \u00e9um lugar de forma\u00e7\u00e3o rochosa elevada que d\u00e1 nome \u00e0 comunidade e fica pr\u00f3ximo das margens do Rio S\u00e3o Francisco, um pouco antes do Balne\u00e1rio de Pedrinhas. Est\u00e1 situado a 18 km do centro de Petrolina (PE) e seu topo alcan\u00e7a 400m de altitude.<\/p>\n<p>A rota a ser seguida para chegar ao Serrote do Urubu \u00e9 a via conhecida como Estrada das Pedrinhas. Ao chegar no distrito que identifica o ponto tur\u00edstico, basta acessar uma estrada de cascalho \u00e0 direita e seguir por mais 1 km.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-891 size-full\" title=\"Mirante Serrote do Urubu Petrolina\" src=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif\" alt=\"Mirante Serrote do Urubu Petrolina\" width=\"680\" height=\"189\" \/><\/p>\n<p>Ao terminar o caminho, estacione e comece uma trilha pelas redondezas para apreciar a vista. Voc\u00ea pode tamb\u00e9m se aproximar da margem e molhar os p\u00e9s no Velho Chico, mas cuidado com a correnteza, que \u00e9 forte. Outra possibilidade \u00e9 escalar a montanha para conquistar uma deslumbrante paisagem composta por ilhas, planta\u00e7\u00f5es, afloramentos rochosos, al\u00e9m da espetacular vista da curva do rio e a cidade de Petrolina (PE) ao fundo.<\/p>\n<h2>Mirante Serrote do Urubu Petrolina o que os Viajantes dizem<\/h2>\n<ul>\n<li>Fa\u00e7a um piquenique ao p\u00f4r do sol com a fam\u00edlia! vale muito a pena! lugar limpo, tranquilo e com uma vista maravilhosa! recomendo!<\/li>\n<li>Simplesmente bel\u00edssima \u00e0 vista de l\u00e1, o contraste da Caatinga com o Rio S\u00e3o Francisco \u00e9 impressionante. O acesso n\u00e3o \u00e9 muito f\u00e1cil mas, vale a pena.<\/li>\n<li>Um excelente ponto para apreciar o por do sol. De Petrolina at\u00e9 l\u00e1 da uns 20km. Um \u00f3timo trajeto para pedalar. Voc\u00ea pode aliar as duas coisas um pedal e apreciar a paisagem.<\/li>\n<li>Para quem vai ao mirante do Serrote do urubu encontra essa bela arte de DEUS,O Contraste entre a caatinga e o Mancial do Velho Chico, isso enche os olhos, voltarei l\u00e1 1.0000,000 de vezes se possivel lindo.<\/li>\n<\/ul>\n<h4>Mapa de localiza\u00e7\u00e3o<\/h4>\n<a class=\"wp-colorbox-iframe\" href=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d31493.93492148301!2d-40.4541619699707!3d-9.35609567588154!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x773651021ea9ed30x52973764b2a416dc!2sSerrotedoUrubuPetrolina-PE!5e0!3m2!1spt-BR!2sbr!4v1634284267556!5m2!1spt-BR!2sbr\"><img decoding=\"async\" src=\"http:\/\/www.encontrapetrolina.com.br\/imgs\/maps-post.png\"><\/a>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O Mirante Serrote do Urubu Petrolina \u00e9um lugar de forma\u00e7\u00e3o rochosa elevada que d\u00e1 nome \u00e0 comunidade e fica pr\u00f3ximo das margens do Rio S\u00e3o Francisco, um pouco antes do Balne\u00e1rio de Pedrinhas. Est\u00e1 situado a 18 km do centro de Petrolina (PE) e seu topo alcan\u00e7a 400m de altitude. A rota a ser seguida para chegar ao Serrote do Urubu \u00e9 a via conhecida como Estrada das Pedrinhas. Ao chegar no distrito que identifica o ponto tur\u00edstico, basta acessar uma estrada de cascalho \u00e0 direita e seguir por mais 1 km. Ao terminar o caminho, estacione e comece uma <\/p>\n","protected":false},"author":1,"featured_media":891,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lugares-em-petrolina","has_thumb"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem<\/title>\n<meta name=\"description\" content=\"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem\" \/>\n<meta property=\"og:description\" content=\"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/\" \/>\n<meta property=\"og:site_name\" content=\"Encontra Petrolina\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T07:52:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Encontra Petrolina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Encontra Petrolina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/\"},\"author\":{\"name\":\"Encontra Petrolina\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"headline\":\"Mirante Serrote do Urubu Petrolina\",\"datePublished\":\"2021-10-15T07:52:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/\"},\"wordCount\":382,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/mirante-do-serrote.gif\",\"articleSection\":[\"Lugares em Petrolina\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/\",\"name\":\"Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/mirante-do-serrote.gif\",\"datePublished\":\"2021-10-15T07:52:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\"},\"description\":\"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/mirante-do-serrote.gif\",\"contentUrl\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/wp-content\\\/uploads\\\/mirante-do-serrote.gif\",\"width\":680,\"height\":189},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/mirante-serrote-do-urubu-petrolina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mirante Serrote do Urubu Petrolina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#website\",\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/\",\"name\":\"Encontra Petrolina\",\"description\":\"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/#\\\/schema\\\/person\\\/0def1354357e30e9d410961df7b6303c\",\"name\":\"Encontra Petrolina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g\",\"caption\":\"Encontra Petrolina\"},\"sameAs\":[\"http:\\\/\\\/www.encontrapetrolina.com.br\"],\"url\":\"https:\\\/\\\/www.encontrapetrolina.com.br\\\/sobre\\\/author\\\/epetrolina\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem","description":"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/","og_locale":"pt_BR","og_type":"article","og_title":"Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem","og_description":"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!","og_url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/","og_site_name":"Encontra Petrolina","article_published_time":"2021-10-15T07:52:32+00:00","og_image":[{"width":680,"height":189,"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif","type":"image\/gif"}],"author":"Encontra Petrolina","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Encontra Petrolina","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#article","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/"},"author":{"name":"Encontra Petrolina","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"headline":"Mirante Serrote do Urubu Petrolina","datePublished":"2021-10-15T07:52:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/"},"wordCount":382,"commentCount":0,"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif","articleSection":["Lugares em Petrolina"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/","name":"Mirante Serrote do Urubu Petrolina: O que os Viajantes Dizem","isPartOf":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#primaryimage"},"image":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif","datePublished":"2021-10-15T07:52:32+00:00","author":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c"},"description":"Veja sobre o ( Mirante Serrote do Urubu em Petrolina ) - Informa\u00e7\u00f5es, o que os viajantes dizem e localiza\u00e7\u00e3o. CLIQUE AQUI!","breadcrumb":{"@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#primaryimage","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif","contentUrl":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-content\/uploads\/mirante-do-serrote.gif","width":680,"height":189},{"@type":"BreadcrumbList","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/mirante-serrote-do-urubu-petrolina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.encontrapetrolina.com.br\/sobre\/"},{"@type":"ListItem","position":2,"name":"Mirante Serrote do Urubu Petrolina"}]},{"@type":"WebSite","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#website","url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/","name":"Encontra Petrolina","description":"Not\u00edcias, eventos, informa\u00e7\u00f5es e dicas da cidade de Petrolina e regi\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.encontrapetrolina.com.br\/sobre\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.encontrapetrolina.com.br\/sobre\/#\/schema\/person\/0def1354357e30e9d410961df7b6303c","name":"Encontra Petrolina","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/083761f87868d6ff0835b3dbedeab77a4918147607895ede66cc5034368d31d0?s=96&d=mm&r=g","caption":"Encontra Petrolina"},"sameAs":["http:\/\/www.encontrapetrolina.com.br"],"url":"https:\/\/www.encontrapetrolina.com.br\/sobre\/author\/epetrolina\/"}]}},"_links":{"self":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=890"}],"version-history":[{"count":1,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/890\/revisions"}],"predecessor-version":[{"id":892,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/posts\/890\/revisions\/892"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media\/891"}],"wp:attachment":[{"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontrapetrolina.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}